{"id":105,"date":"2026-05-13T15:31:33","date_gmt":"2026-05-13T18:31:33","guid":{"rendered":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/"},"modified":"2026-05-13T15:31:34","modified_gmt":"2026-05-13T18:31:34","slug":"obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja","status":"publish","type":"post","link":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/","title":{"rendered":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja"},"content":{"rendered":"<p><\/p>\n<div>\n<p>La qu\u00eate de l&#8217;industrie du ma\u00efs pour faire entrer davantage de biocarburant dans les pompes \u00e0 essence am\u00e9ricaines se heurte \u00e0 de nouveaux obstacles \u00e0 quelques heures seulement d\u2019un vote de la Chambre des repr\u00e9sentants sur un projet de loi visant \u00e0 autoriser les ventes annuelles de m\u00e9langes d\u2019\u00e9thanol \u00e0 15 % dans l\u2019essence.<\/p>\n<p>Une nouvelle \u00e9tude de l\u2019Institut de recherche sur les politiques alimentaires et agricoles (FAPRI) de l\u2019Universit\u00e9 du Missouri indique que permettre des ventes annuelles, volontaires, de concentrations plus \u00e9lev\u00e9es d\u2019\u00e9thanol contenu dans les carburants pour moteurs, connu sous le nom d\u2019E15, conduirait \u00e0 une utilisation plus importante de carburant \u00e0 base de ma\u00efs pour satisfaire les quotas nationaux de biocarburants, au d\u00e9triment du diesel \u00e0 base de biomasse, un carburant qui d\u00e9pend fortement de l\u2019huile de soja comme ingr\u00e9dient cl\u00e9.<\/p>\n<p>La structure des mandats du Renewable Fuel Standard (RFS) signifie aussi \u00ab une demande plus \u00e9lev\u00e9e de ma\u00efs et une demande plus faible d\u2019huile de soja et de soja \u00bb, selon les recherches co-r\u00e9dig\u00e9es par le responsable du FAPRI, Seth Meyer, qui occupait jusqu\u2019\u00e0 l\u2019an dernier le poste d\u2019\u00e9conomiste en chef du USDA (Department of Agriculture des \u00c9tats\u2011Unis).<\/p>\n<p>Les r\u00e9sultats ont conduit l\u2019American Soybean Association \u00e0 recommander en priv\u00e9 \u00e0 ses adh\u00e9rents qu\u2019elle ne peut pas soutenir le texte actuel sur l\u2019E15. Bloomberg News avait pr\u00e9c\u00e9demment fait \u00e9tat de ce courriel interne.<\/p>\n<p>En plus d\u2019autoriser l\u2019E15 toute l\u2019ann\u00e9e, le texte qui doit \u00eatre soumis au vote mercredi pr\u00e9voit \u00e9galement de r\u00e9viser la fa\u00e7on dont les exemptions accord\u00e9es aux petits raffineurs dans le cadre du RFS sont g\u00e9r\u00e9es par l\u2019Environmental Protection Agency (EPA), une proposition oppos\u00e9e par les raffineurs ind\u00e9pendants.<\/p>\n<p>Lorsque le dernier plan E15 a \u00e9t\u00e9 d\u00e9voil\u00e9 le mois dernier, l\u2019ASA a d\u00e9clar\u00e9 qu\u2019elle \u00e9valuait encore les effets potentiels sur les biocarburants \u00e0 base de soja et sur les agriculteurs. Le groupe est depuis rest\u00e9 publiquement neutre sur la question.<\/p>\n<p>Le projet de loi reviendrait sur des r\u00e8gles interdisant les ventes de m\u00e9langes d\u2019\u00e9thanol plus \u00e9lev\u00e9s pendant les mois d\u2019\u00e9t\u00e9 en raison de pr\u00e9occupations li\u00e9es au smog qui sont aujourd\u2019hui largement consid\u00e9r\u00e9es comme d\u00e9pass\u00e9es. Au cours de son premier mandat, le pr\u00e9sident Donald Trump avait autoris\u00e9 l\u2019E15 toute l\u2019ann\u00e9e par d\u00e9cret, bien que cette mesure ait \u00e9t\u00e9 annul\u00e9e plus tard par une d\u00e9cision judiciaire affirmant que le Congr\u00e8s devait d\u00e9cider de la question. Au cours des derni\u00e8res ann\u00e9es, l\u2019EPA a d\u00e9livr\u00e9 des d\u00e9rogations \u00e0 la vente estivale d\u2019E15.<\/p>\n<p>Le texte, parrain\u00e9 par le repr\u00e9sentant Adrian Smith, r\u00e9publicain du Nebraska, \u00ab offrirait cette certitude r\u00e9glementaire \u00bb, a d\u00e9clar\u00e9 Werner. \u00ab Il y a beaucoup de stations\u2011service qui aimeraient proposer l\u2019E15. \u2026 Nous ne voulons pas devoir d\u00e9pendre d\u2019aller \u00e0 l\u2019EPA chaque ann\u00e9e pour demander une d\u00e9rogation d\u2019urgence. \u00bb<\/p>\n<p>L\u2019ambiance avant le vote est \u00ab prudemment optimiste \u00bb, a d\u00e9clar\u00e9 Werner, ajoutant que la flamb\u00e9e des prix de l\u2019essence aide les groupes \u00e9thnols \u00e0 faire valoir leur argument en faveur du texte.<\/p>\n<p>\u00ab Il est tr\u00e8s clair pour nous que les gens pensent et parlent des prix \u00e9nerg\u00e9tiques \u00e9lev\u00e9s en ce moment \u00bb, a\u2011t\u2011il d\u00e9clar\u00e9. \u00ab Tandis que ces prix \u00e9lev\u00e9s du gaz persistent, c\u2019est un levier assez simple \u00e0 actionner qui offrirait vraiment cette option. Nous esp\u00e9rons que ce message r\u00e9sonne. \u00bb<\/p>\n<p>Les l\u00e9gislateurs r\u00e9publicains sont divis\u00e9s sur l\u2019E15, avec une forte opposition de certains d\u00e9put\u00e9s issus d\u2019\u00c9tats o\u00f9 le raffinage lourd du p\u00e9trole est important. Les R\u00e9publicains ne m\u00e8neront pas un comptage des soutiens sur le texte \u00e9thanol, m\u00eame si le porte-parole adjoint de la majorit\u00e9 \u00e0 la Chambre, Tom Emmer, r\u00e9publicain du Minnesota, a clairement indiqu\u00e9 qu\u2019il soutiendrait le texte.<\/p>\n<p>\u00ab J\u2019ai toujours soutenu l\u2019E15 toute l\u2019ann\u00e9e et je suis fier de voter \u00ab oui \u00bb sur le parquet de la Chambre plus tard aujourd\u2019hui pour soutenir les agriculteurs et les producteurs du Minnesota \u00bb, a d\u00e9clar\u00e9 Emmer dans un communiqu\u00e9.<\/p>\n<p><em>Noah Wicks contributed to this story.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"class_list":["post-105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\" \/>\n<meta property=\"og:site_name\" content=\"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T18:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T18:31:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tom\u00e1s Echeverr\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tom\u00e1s Echeverr\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\"},\"author\":{\"name\":\"Tom\u00e1s Echeverr\u00eda\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/6f778d1f6f2c0c1b373aeda7620b7ce3\"},\"headline\":\"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja\",\"datePublished\":\"2026-05-13T18:31:33+00:00\",\"dateModified\":\"2026-05-13T18:31:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\"},\"wordCount\":748,\"publisher\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#organization\"},\"image\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg\",\"keywords\":[\"avant\",\"Chambre\",\"des\",\"\u00e9tude\",\"lE15\",\"limpact\",\"Obstacles\",\"repr\u00e9sentants\",\"soja\",\"sur\",\"Vote\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\",\"name\":\"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\",\"isPartOf\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg\",\"datePublished\":\"2026-05-13T18:31:33+00:00\",\"dateModified\":\"2026-05-13T18:31:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg\",\"contentUrl\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg\",\"width\":835,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Arg-Agro\",\"item\":\"https:\/\/arg-agro.com.ar\/actualidad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#website\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/\",\"name\":\"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arg-agro.com.ar\/actualidad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#organization\",\"name\":\"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/store_logo.png\",\"contentUrl\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/store_logo.png\",\"width\":270,\"height\":90,\"caption\":\"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro\"},\"image\":{\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/6f778d1f6f2c0c1b373aeda7620b7ce3\",\"name\":\"Tom\u00e1s Echeverr\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/Tomas-Echeverria-150x150.jpg\",\"contentUrl\":\"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/Tomas-Echeverria-150x150.jpg\",\"caption\":\"Tom\u00e1s Echeverr\u00eda\"},\"description\":\"Tom\u00e1s Echeverr\u00eda es especialista en agricultura y manejo sostenible de suelos, con experiencia en sistemas productivos de Argentina. Investiga la optimizaci\u00f3n del riego, la nutrici\u00f3n de cultivos y la adopci\u00f3n de tecnolog\u00edas de agricultura de precisi\u00f3n para mejorar rendimientos. En Arg-Agro, divulga pr\u00e1cticas basadas en evidencia para una producci\u00f3n eficiente y resiliente.\",\"sameAs\":[\"https:\/\/arg-agro.com.ar\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/","og_locale":"es_ES","og_type":"article","og_title":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","og_url":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/","og_site_name":"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","article_published_time":"2026-05-13T18:31:33+00:00","article_modified_time":"2026-05-13T18:31:34+00:00","og_image":[{"width":835,"height":627,"url":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg","type":"image\/jpeg"}],"author":"Tom\u00e1s Echeverr\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Tom\u00e1s Echeverr\u00eda","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#article","isPartOf":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/"},"author":{"name":"Tom\u00e1s Echeverr\u00eda","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/6f778d1f6f2c0c1b373aeda7620b7ce3"},"headline":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja","datePublished":"2026-05-13T18:31:33+00:00","dateModified":"2026-05-13T18:31:34+00:00","mainEntityOfPage":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/"},"wordCount":748,"publisher":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/#organization"},"image":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage"},"thumbnailUrl":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg","keywords":["avant","Chambre","des","\u00e9tude","lE15","limpact","Obstacles","repr\u00e9sentants","soja","sur","Vote"],"articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/","url":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/","name":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja - ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","isPartOf":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage"},"image":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage"},"thumbnailUrl":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg","datePublished":"2026-05-13T18:31:33+00:00","dateModified":"2026-05-13T18:31:34+00:00","breadcrumb":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#primaryimage","url":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg","contentUrl":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/05\/Obstacles-a-lE15-avant-le-vote-de-la-Chambre-des.jpg","width":835,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/arg-agro.com.ar\/actualidad\/obstacles-a-le15-avant-le-vote-de-la-chambre-des-representants-etude-sur-limpact-du-soja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Arg-Agro","item":"https:\/\/arg-agro.com.ar\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Obstacles \u00e0 l\u2019E15 avant le vote de la Chambre des repr\u00e9sentants, \u00e9tude sur l\u2019impact du soja"}]},{"@type":"WebSite","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#website","url":"https:\/\/arg-agro.com.ar\/actualidad\/","name":"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","description":"","publisher":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arg-agro.com.ar\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#organization","name":"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro","url":"https:\/\/arg-agro.com.ar\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/store_logo.png","contentUrl":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/store_logo.png","width":270,"height":90,"caption":"ARG-AGRO Semilleria Venta de Semillas e Insumos para el Agro"},"image":{"@id":"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/6f778d1f6f2c0c1b373aeda7620b7ce3","name":"Tom\u00e1s Echeverr\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arg-agro.com.ar\/actualidad\/#\/schema\/person\/image\/","url":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/Tomas-Echeverria-150x150.jpg","contentUrl":"https:\/\/arg-agro.com.ar\/actualidad\/wp-content\/uploads\/2026\/03\/Tomas-Echeverria-150x150.jpg","caption":"Tom\u00e1s Echeverr\u00eda"},"description":"Tom\u00e1s Echeverr\u00eda es especialista en agricultura y manejo sostenible de suelos, con experiencia en sistemas productivos de Argentina. Investiga la optimizaci\u00f3n del riego, la nutrici\u00f3n de cultivos y la adopci\u00f3n de tecnolog\u00edas de agricultura de precisi\u00f3n para mejorar rendimientos. En Arg-Agro, divulga pr\u00e1cticas basadas en evidencia para una producci\u00f3n eficiente y resiliente.","sameAs":["https:\/\/arg-agro.com.ar\/"]}]}},"_links":{"self":[{"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/posts\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":1,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/posts\/105\/revisions"}],"predecessor-version":[{"id":107,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/posts\/105\/revisions\/107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/media\/106"}],"wp:attachment":[{"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arg-agro.com.ar\/actualidad\/wp-json\/wp\/v2\/categories?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}